{"id":209495,"date":"2021-11-22T16:03:55","date_gmt":"2021-11-22T22:03:55","guid":{"rendered":"https:\/\/www.agrolytics.org\/specie\/boldaab2671\/"},"modified":"2021-11-22T16:03:55","modified_gmt":"2021-11-22T22:03:55","slug":"boldaab2671","status":"publish","type":"specie","link":"https:\/\/agrolytics.org\/info\/specie\/boldaab2671\/","title":{"rendered":"BOLD:AAB2671"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"class_list":["post-209495","specie","type-specie","status-publish","format-standard","hentry","category-animalia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BOLD:AAB2671 - Agrolytics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrolytics.org\/info\/specie\/boldaab2671\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BOLD:AAB2671 - Agrolytics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrolytics.org\/info\/specie\/boldaab2671\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrolytics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BOLD:AAB2671 - Agrolytics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrolytics.org\/info\/specie\/boldaab2671\/","og_locale":"es_MX","og_type":"article","og_title":"BOLD:AAB2671 - Agrolytics","og_url":"https:\/\/agrolytics.org\/info\/specie\/boldaab2671\/","og_site_name":"Agrolytics","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agrolytics.org\/info\/specie\/boldaab2671\/","url":"https:\/\/agrolytics.org\/info\/specie\/boldaab2671\/","name":"BOLD:AAB2671 - Agrolytics","isPartOf":{"@id":"https:\/\/agrolytics.org\/info\/#website"},"datePublished":"2021-11-22T22:03:55+00:00","breadcrumb":{"@id":"https:\/\/agrolytics.org\/info\/specie\/boldaab2671\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrolytics.org\/info\/specie\/boldaab2671\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/agrolytics.org\/info\/specie\/boldaab2671\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/agrolytics.org\/info\/"},{"@type":"ListItem","position":2,"name":"BOLD:AAB2671"}]},{"@type":"WebSite","@id":"https:\/\/agrolytics.org\/info\/#website","url":"https:\/\/agrolytics.org\/info\/","name":"Agrolytics","description":"Inteligencia agroambiental","publisher":{"@id":"https:\/\/agrolytics.org\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrolytics.org\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrolytics.org\/info\/#organization","name":"Agrolytics","url":"https:\/\/agrolytics.org\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrolytics.org\/info\/#\/schema\/logo\/image\/","url":"https:\/\/agrolytics.org\/info\/wp-content\/uploads\/2019\/06\/logo-agrolytics.png","contentUrl":"https:\/\/agrolytics.org\/info\/wp-content\/uploads\/2019\/06\/logo-agrolytics.png","width":164,"height":164,"caption":"Agrolytics"},"image":{"@id":"https:\/\/agrolytics.org\/info\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/specie\/209495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/specie"}],"about":[{"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/types\/specie"}],"replies":[{"embeddable":true,"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/comments?post=209495"}],"version-history":[{"count":0,"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/specie\/209495\/revisions"}],"wp:attachment":[{"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/media?parent=209495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/categories?post=209495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}