{"id":209016,"date":"2021-11-18T23:36:13","date_gmt":"2021-11-19T05:36:13","guid":{"rendered":"https:\/\/www.agrolytics.org\/specie\/brueelia_atricapilla\/"},"modified":"2021-11-18T23:36:13","modified_gmt":"2021-11-19T05:36:13","slug":"brueelia_atricapilla","status":"publish","type":"specie","link":"https:\/\/agrolytics.org\/info\/specie\/brueelia_atricapilla\/","title":{"rendered":"Brueelia atricapilla"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"class_list":["post-209016","specie","type-specie","status-publish","format-standard","hentry","category-animalia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brueelia atricapilla - Agrolytics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrolytics.org\/info\/specie\/brueelia_atricapilla\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brueelia atricapilla - Agrolytics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrolytics.org\/info\/specie\/brueelia_atricapilla\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrolytics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brueelia atricapilla - Agrolytics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrolytics.org\/info\/specie\/brueelia_atricapilla\/","og_locale":"es_MX","og_type":"article","og_title":"Brueelia atricapilla - Agrolytics","og_url":"https:\/\/agrolytics.org\/info\/specie\/brueelia_atricapilla\/","og_site_name":"Agrolytics","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agrolytics.org\/info\/specie\/brueelia_atricapilla\/","url":"https:\/\/agrolytics.org\/info\/specie\/brueelia_atricapilla\/","name":"Brueelia atricapilla - Agrolytics","isPartOf":{"@id":"https:\/\/agrolytics.org\/info\/#website"},"datePublished":"2021-11-19T05:36:13+00:00","breadcrumb":{"@id":"https:\/\/agrolytics.org\/info\/specie\/brueelia_atricapilla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrolytics.org\/info\/specie\/brueelia_atricapilla\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/agrolytics.org\/info\/specie\/brueelia_atricapilla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/agrolytics.org\/info\/"},{"@type":"ListItem","position":2,"name":"Brueelia atricapilla"}]},{"@type":"WebSite","@id":"https:\/\/agrolytics.org\/info\/#website","url":"https:\/\/agrolytics.org\/info\/","name":"Agrolytics","description":"Inteligencia agroambiental","publisher":{"@id":"https:\/\/agrolytics.org\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrolytics.org\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrolytics.org\/info\/#organization","name":"Agrolytics","url":"https:\/\/agrolytics.org\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrolytics.org\/info\/#\/schema\/logo\/image\/","url":"https:\/\/agrolytics.org\/info\/wp-content\/uploads\/2019\/06\/logo-agrolytics.png","contentUrl":"https:\/\/agrolytics.org\/info\/wp-content\/uploads\/2019\/06\/logo-agrolytics.png","width":164,"height":164,"caption":"Agrolytics"},"image":{"@id":"https:\/\/agrolytics.org\/info\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/specie\/209016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/specie"}],"about":[{"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/types\/specie"}],"replies":[{"embeddable":true,"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/comments?post=209016"}],"version-history":[{"count":0,"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/specie\/209016\/revisions"}],"wp:attachment":[{"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/media?parent=209016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrolytics.org\/info\/wp-json\/wp\/v2\/categories?post=209016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}